{"id":2586,"date":"2020-10-23T01:44:54","date_gmt":"2020-10-23T01:44:54","guid":{"rendered":"https:\/\/www.dflift.com\/?p=2586"},"modified":"2024-11-21T06:22:33","modified_gmt":"2024-11-21T06:22:33","slug":"electric-stacker","status":"publish","type":"post","link":"https:\/\/www.dflift.com\/fr\/electric-stacker\/","title":{"rendered":"Gerbeur \u00e9lectrique"},"content":{"rendered":"<div class=\"content\">\r\n<div class=\"content-block\">\r\n<h3>Introduction<\/h3>\r\n<p>Le levage et le fonctionnement du gerbeur \u00e9lectrique sont aliment\u00e9s par la batterie, ce qui am\u00e9liore l'efficacit\u00e9 du travail et r\u00e9duit l'intensit\u00e9 du travail. Compar\u00e9 \u00e0 la taille du chariot \u00e9l\u00e9vateur, il peut travailler dans un espace \u00e9troit. Sans bruit, \u00e9conome en \u00e9nergie, respectueux de l'environnement et peu co\u00fbteux, le gerbeur \u00e9lectrique est l'outil de manutention le plus adapt\u00e9 \u00e0 la logistique moderne et \u00e0 l'industrie de l'entreposage.<\/p>\r\n<\/div>\r\n<div class=\"content-block\">\r\n<h3>Contr\u00f4leur<\/h3>\r\n<img loading=\"lazy\" src=\"https:\/\/www.dflift.com\/wp-content\/uploads\/2020\/10\/Controller.jpg\" alt=\"\" width=\"760\" height=\"584\" class=\"alignnone wp-image-2587\" \/>\r\n<ul>\r\n\t<li>Interrupteur de marche arri\u00e8re d'urgence<\/li>\r\n\t<li>Commutation avant et arri\u00e8re<\/li>\r\n\t<li>Corne<\/li>\r\n\t<li>Mont\u00e9e des fourches<\/li>\r\n\t<li>Fourche vers le bas<\/li>\r\n<\/ul>\r\n<\/div>\r\n<div class=\"content-block\">\r\n<h3>Avantages<\/h3>\r\n<ul>\r\n\t<li>Poign\u00e9e d\u00e9cal\u00e9e, corps compact, adapt\u00e9 aux all\u00e9es \u00e9troites.<\/li>\r\n\t<li>Moteur sans balai \u00e0 aimant permanent.<\/li>\r\n\t<li>Batterie au plomb sans entretien\/en option : batterie au lithium.<\/li>\r\n\t<li>Unit\u00e9 hydraulique antid\u00e9flagrante.<\/li>\r\n\t<li>Chargeur externe intelligent.<\/li>\r\n\t<li>Le temps de travail \u00e0 pleine charge est sup\u00e9rieur \u00e0 5 heures<\/li>\r\n<\/ul>\r\n<\/div>\r\n<div class=\"content-block\">\r\n<h3>Param\u00e8tres<\/h3>\r\n\r\n<div class=\"custom_tables\"><table class=\"tg\">\n<thead>\n<tr>\n<th rowspan=\"3\"><\/th>\n<th style=\"text-align: left;\">Mod\u00e8le<\/th>\n<th><\/th>\n<th>EPS15-20<\/th>\n<th>EPS15-25<\/th>\n<th>EPS15-30<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: left;\">Type de puissance<\/th>\n<th><\/th>\n<th colspan=\"3\">Batterie au plomb sans entretien (batterie au lithium)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: left;\">Type d'op\u00e9ration<\/th>\n<th><\/th>\n<th colspan=\"3\">Contr\u00f4le \u00e9lectrique complet<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td rowspan=\"4\">FEATURES<\/td>\n<td>Capacit\u00e9 de charge<\/td>\n<td>kg<\/td>\n<td colspan=\"3\">1500<\/td>\n<\/tr>\n<tr>\n<td>Centre de charge<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">400<\/td>\n<\/tr>\n<tr>\n<td>Hauteur de levage<\/td>\n<td>mm<\/td>\n<td>2000<\/td>\n<td>2500<\/td>\n<td>3000<\/td>\n<\/tr>\n<tr>\n<td>Empattement<\/td>\n<td>mm<\/td>\n<td>1151<\/td>\n<td>1151<\/td>\n<td>1151<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"7\">DIMENSIONS<\/td>\n<td>Dimension globale (L\u00d7W)<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">1730\u00d7800<\/td>\n<\/tr>\n<tr>\n<td>Hauteur totale<\/td>\n<td>mm<\/td>\n<td>1580\/2550<\/td>\n<td>2030\/3250<\/td>\n<td>2630\u00d73750<\/td>\n<\/tr>\n<tr>\n<td>Dimension de la fourche<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">1080\u00d7140\u00d760<\/td>\n<\/tr>\n<tr>\n<td>Largeur de la fourche Min.\/Max.<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">550\/685<\/td>\n<\/tr>\n<tr>\n<td>Min. Garde au sol<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">5<\/td>\n<\/tr>\n<tr>\n<td>Rayon de braquage<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">1410<\/td>\n<\/tr>\n<tr>\n<td>Largeur du canal (plateau de 1000*1200mm)<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">1000<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">POIDS<\/td>\n<td>Poids propre (avec batterie)<\/td>\n<td>kg<\/td>\n<td>500<\/td>\n<td>540<\/td>\n<td>620<\/td>\n<\/tr>\n<tr>\n<td>Poids de la batterie<\/td>\n<td>kg<\/td>\n<td colspan=\"3\">52<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"7\">ROUE<\/td>\n<td>Type de roue (conduite\/rotation)<\/td>\n<td><\/td>\n<td colspan=\"3\">PU solide<\/td>\n<\/tr>\n<tr>\n<td>Tailles des roues motrices<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">210\u00d770<\/td>\n<\/tr>\n<tr>\n<td>Roue auxiliaire Tailles<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">110\u00d755<\/td>\n<\/tr>\n<tr>\n<td>Tailles des roues de chargement<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">80\u00d770<\/td>\n<\/tr>\n<tr>\n<td>Empattement avant<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">530<\/td>\n<\/tr>\n<tr>\n<td>Empattement arri\u00e8re<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">503<\/td>\n<\/tr>\n<tr>\n<td>Garde au sol minimale<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">30<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\">Unit\u00e9s de puissance et commandes<\/td>\n<td>Puissance nominale du moteur d'entra\u00eenement<\/td>\n<td>kw(60min)<\/td>\n<td colspan=\"3\">0.8<\/td>\n<\/tr>\n<tr>\n<td>Puissance du moteur de levage<\/td>\n<td>kw(60min)<\/td>\n<td colspan=\"3\">2.2<\/td>\n<\/tr>\n<tr>\n<td>Dimension de la batterie<\/td>\n<td>mm<\/td>\n<td colspan=\"3\">271\u00d7174\u00d7213<\/td>\n<\/tr>\n<tr>\n<td>Tension\/Capacit\u00e9 de la batterie<\/td>\n<td>V\/ah<\/td>\n<td colspan=\"3\">24\/70<\/td>\n<\/tr>\n<tr>\n<td>Pression de travail<\/td>\n<td>mpa<\/td>\n<td colspan=\"3\">12<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"7\">Param\u00e8tres de performance<\/td>\n<td>Vitesse de conduite \u00e0 vide\/en charge<\/td>\n<td>km\/h<\/td>\n<td colspan=\"3\">4\/4.5<\/td>\n<\/tr>\n<tr>\n<td>Vitesse de levage \u00e0 vide\/en charge<\/td>\n<td>mm\/s<\/td>\n<td colspan=\"3\">45\/55<\/td>\n<\/tr>\n<tr>\n<td>Vitesse de descente \u00e0 vide\/en charge<\/td>\n<td>mm\/s<\/td>\n<td colspan=\"3\">40\/55<\/td>\n<\/tr>\n<tr>\n<td>Effort de traction nominal<\/td>\n<td>kN<\/td>\n<td colspan=\"3\">1.1<\/td>\n<\/tr>\n<tr>\n<td>Capacit\u00e9 maximale d'escalade<\/td>\n<td>%<\/td>\n<td colspan=\"3\">5\/7<\/td>\n<\/tr>\n<tr>\n<td>Type de frein de translation<\/td>\n<td><\/td>\n<td colspan=\"3\">l'induction \u00e9lectromagn\u00e9tique<\/td>\n<\/tr>\n<tr>\n<td>Type de frein de stationnement<\/td>\n<td><\/td>\n<td colspan=\"3\">l'induction \u00e9lectromagn\u00e9tique<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">Autres<\/td>\n<td>Type de commande de l'entra\u00eenement<\/td>\n<td><\/td>\n<td colspan=\"3\">\u00c9lectrique<\/td>\n<\/tr>\n<tr>\n<td>Type de direction<\/td>\n<td><\/td>\n<td colspan=\"3\">Manuel<\/td>\n<\/tr>\n<tr>\n<td>Niveau de bruit<\/td>\n<td>dB<\/td>\n<td colspan=\"3\">68<\/td>\n<\/tr>\n<tr>\n<td>Indice d'imperm\u00e9abilit\u00e9<\/td>\n<td><\/td>\n<td colspan=\"3\">IP54<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div>\r\n<!-- \/ content-block -->\r\n<div class=\"content-block\">\r\n<h3>SALON DES PI\u00c8CES D\u00c9TACH\u00c9ES<\/h3>\r\n<div class=\"grid\">\r\n\t\t\t[notphone]\r\n\t\t\t[symmen_img_gallery id=\"1\"]\r\n\t\t\t\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<div class=\"grid-3\">\r\n<img src=\"img_url\" width=\"228\" height=\"152\" alt=\"\">\r\n<p>img_desc<\/p>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t[\/symmen_img_gallery]\r\n\t\t\t[\/notphone]\r\n\t\t\t[phone]\r\n\t\t\t[symmen_img_gallery id=\"1\"]\r\n\t\t\t\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<div class=\"grid-3\">\r\n<img src=\"img_url\" width=\"320\" height=\"214\" alt=\"\">\r\n<p style=\"height:.96rem\">img_desc<\/p>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t[\/symmen_img_gallery]\r\n\t\t\t[\/phone]\r\n\t\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<!-- \/ content -->","protected":false},"excerpt":{"rendered":"Introduction The lifting and operation of the electric stacker are driven by the battery, which improves the working efficiency and reduces the working intensity. Compared with the size of the forklift truck, it can work in a narrow space. With no noise, energy saving and environmental protection, and low-cost characteristics, electric stacker is the most [&hellip;]","protected":false},"author":5,"featured_media":5882,"parent":2583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35,69],"tags":[87],"_links":{"self":[{"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/posts\/2586"}],"collection":[{"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/comments?post=2586"}],"version-history":[{"count":13,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/posts\/2586\/revisions"}],"predecessor-version":[{"id":11273,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/posts\/2586\/revisions\/11273"}],"up":[{"embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/posts\/2583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/media\/5882"}],"wp:attachment":[{"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/media?parent=2586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/categories?post=2586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dflift.com\/fr\/wp-json\/wp\/v2\/tags?post=2586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}